{"id":6,"date":"2020-10-29T08:43:43","date_gmt":"2020-10-29T08:43:43","guid":{"rendered":"https:\/\/qi54.qodeinteractive.com\/?page_id=6"},"modified":"2026-04-06T18:48:27","modified_gmt":"2026-04-06T18:48:27","slug":"home","status":"publish","type":"page","link":"https:\/\/hero-tonic.com\/es\/","title":{"rendered":"Inicio"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"6\" class=\"elementor elementor-6\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3d97c1f elementor-section-full_width elementor-section-items-stretch elementor-section-height-full elementor-section-height-default qodef-elementor-content-no\" data-id=\"3d97c1f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2c7a944\" data-id=\"2c7a944\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf74cc6 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"cf74cc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t<h1 class=\"qodef-m-title\">\n\t\tH\u00c9ROE <span class=\"qodef-e-colored\">T\u00d3NICO<\/span>\t<\/h1>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40df889 elementor-widget__width-auto elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"40df889\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t<p class=\"qodef-m-subtitle\">\n\t\tMEMBRES\u00cdA\t\t\t<\/p>\n\t\t\t<h3 class=\"qodef-m-title\">\n\t\t$24,95 al mes\t<\/h3>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-96c7d43 elementor-section-full_width elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"96c7d43\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-517bc5e\" data-id=\"517bc5e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e8a0dae elementor-section-boxed elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"e8a0dae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f863fd9\" data-id=\"f863fd9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e818d5 elementor-widget-tablet__width-inherit elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"4e818d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t<h2 class=\"qodef-m-title\">\n\t\tAPASIONADOS EXPERTOS<br \/> ENERGIZANTE <span class=\"qodef-e-colored\">VIVE.<\/span>\t<\/h2>\n\t\t\t<div class=\"qodef-m-text\"><p>Para siempre que uno pueda entender la verdad eterna. Nam, mi preocupaci\u00f3n por un Paulo delicado y malicioso, y mi preocupaci\u00f3n por un placer enga\u00f1oso. Si la equidad es forense, cuando se escuchan f\u00e1bulas enga\u00f1osas, mi molestia se congela. En cuanto a las viejas verdades, sea la mayor explicaci\u00f3n para m\u00ed. Permite que todo deleite sea conocido, como si los derechos fueran los que debieran ser.<\/p><\/div>\n\t\t<div class=\"qodef-m-button qodef-qi-clear\">\n\t\t\t<a class=\"qodef-shortcode qodef-m qodef-qi-button qodef-html--link qodef-layout--filled qodef-type--standard qodef-icon--right qodef-hover--icon-move-horizontal-short\" href=\"https:\/\/hero-tonic.com\/es\/classes-timetable\/\" target=\"_self\">\t\t<span class=\"qodef-m-text\">Ver programa<\/span>\t\t\t<\/a>\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-27e455c\" data-id=\"27e455c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f3788d9 elementor-section-boxed elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"f3788d9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f51fe6f\" data-id=\"f51fe6f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9318746 elementor-widget__width-initial elementor-widget elementor-widget-qi_addons_for_elementor_icon_with_text\" data-id=\"9318746\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_icon_with_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-icon-with-text qodef-layout--top qodef--custom-icon qodef-alignment--center\" >\n\t\t\t<div class=\"qodef-m-icon-wrapper\">\n\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/hero-tonic.com\/es\/products\/\" target=\"_self\">\n\t<div class=\"qodef-m-icon-holder\">\n\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 92.6 85.2\" style=\"enable-background:new 0 0 92.6 85.2; stroke:transparent;\" xml:space=\"preserve\"><path d=\"M91.2,47.9l-7.3,0c1.2-1.3,2.3-2.6,3.3-3.9c1.4-1.9,3.1-5.9,3.5-11.1c0.3-4-0.1-10-3.7-15.5  c-2.4-3.6-5.9-6.6-10-8.5c-4.6-2.1-9.5-2.6-14.3-1.5c-4.5,1-8.6,3.4-11.8,6.8c-2,2.2-3.5,4.7-4.6,7.4c-1-2.7-2.6-5.2-4.6-7.4  c-3.2-3.5-7.3-5.8-11.8-6.8c-4.8-1.1-9.7-0.5-14.3,1.5c-4.1,1.9-7.6,4.9-10,8.5c-3.7,5.6-4,11.5-3.7,15.5C2.3,38.1,4,42.1,5.4,44  c1.1,1.5,2.4,3.1,3.9,4.6H1.3C0.6,48.6,0,49.2,0,50c0,0.7,0.6,1.3,1.3,1.3h10.7c4.5,4.2,10.1,8.3,15.8,12.7  c6,4.5,12.3,9.2,17.5,14.1c0.3,0.2,0.6,0.4,0.9,0.4c0.3,0,0.7-0.1,0.9-0.4c5.2-4.8,11.4-9.5,17.5-14.1c6.1-4.5,11.9-8.9,16.5-13.3  l10-0.1c0.7,0,1.3-0.6,1.3-1.4C92.6,48.5,91.9,47.9,91.2,47.9z M7.6,42.4c-2.7-3.7-5.5-14.8,0.3-23.6c3.2-4.9,9.7-9.4,17.2-9.4  c1.4,0,2.8,0.1,4.2,0.5c8.1,1.8,14.4,8.7,15.6,17c0.1,0.7,0.7,1.1,1.3,1.1s1.2-0.5,1.3-1.1c1.2-8.4,7.5-15.2,15.6-17  c9.3-2.1,17.7,3.1,21.5,8.9c5.8,8.7,3,19.9,0.3,23.6c-1.3,1.8-3,3.7-4.9,5.5l-18,0.1l-5.5-11.5c-0.2-0.5-0.8-0.8-1.3-0.8  c-0.6,0-1,0.4-1.2,1l-5.4,19.5l-13.4-32c-0.2-0.5-0.7-0.9-1.3-0.8c-0.6,0-1.1,0.4-1.2,0.9L25,48.6H13.1C10.9,46.5,9.1,44.5,7.6,42.4  z M63,61.8c-5.7,4.3-11.7,8.8-16.8,13.4c-5.1-4.6-11-9.1-16.8-13.4c-4.8-3.6-9.4-7.1-13.4-10.5H26c0.6,0,1.1-0.4,1.3-0.9l6.9-21.7  l13.5,32.2c0.2,0.5,0.7,0.8,1.2,0.8c0,0,0.1,0,0.1,0c0.6,0,1.1-0.4,1.2-1L55.7,41l4.3,9c0.2,0.5,0.7,0.8,1.2,0.8c0,0,0,0,0,0  l15.9-0.1C73,54.3,68.1,58,63,61.8z\"><\/path><\/svg>\t<\/div>\n\t<\/a>\n\t\t<\/div>\n\t\t<div class=\"qodef-m-content\">\n\t\t\t\t\t<h5 class=\"qodef-m-title\">\n\t\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/hero-tonic.com\/es\/products\/\" target=\"_self\">\n\t\t\t\t\t<span class=\"qodef-m-title-text\">asesor\u00eda nutricional<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t<\/h5>\n\t\t\t<div class=\"qodef-m-text\">\u00bfQui\u00e9n sufre tantos males, a\u00fan se atrever\u00eda a nombrarnos justos?.<\/div>\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-aad7b1e\" data-id=\"aad7b1e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63f4a60 elementor-widget__width-initial elementor-widget elementor-widget-qi_addons_for_elementor_icon_with_text\" data-id=\"63f4a60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_icon_with_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-icon-with-text qodef-layout--top qodef--custom-icon qodef-alignment--center\" >\n\t\t\t<div class=\"qodef-m-icon-wrapper\">\n\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/hero-tonic.com\/es\/products\/\" target=\"_self\">\n\t<div class=\"qodef-m-icon-holder\">\n\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 92.6 85.2\" style=\"enable-background:new 0 0 92.6 85.2; stroke:transparent;\" xml:space=\"preserve\"><g>\t<path d=\"M79.5,26.7c-3.4-2.4-7.7-3.8-12.7-3.9c-4.7-0.1-9.9,0.8-15.6,2.7c-11.4-3.8-20.9-3.6-27.5,0.7   c-3.1,2-5.4,4.7-7,8.2c-2.5-0.1-8.5,0-11.1,2.4c-0.8,0.8-1.2,1.7-1.2,2.8v18.9c0,0.3,0.1,1.6,1.3,2.8c1.7,1.8,5,2.8,9.6,2.8   c0,0,0.1,0,0.1,0c0,0,0,0,0,0c0.1,0,0.1,0,0.2,0h2.7c5.1,9.4,14,16.7,23.7,19.5c3,0.9,6.1,1.3,9.1,1.3c20.3,0,36.9-16.6,36.9-36.9   C88.2,38.2,85.2,30.8,79.5,26.7z M15.7,37.1c-0.5,1.7-0.9,3.4-1.1,5.4c-4.5-0.3-6.7-2.4-7.4-3.3c0.1-0.1,0.1-0.3,0.3-0.5   C8.9,37.5,12.7,37.1,15.7,37.1z M7.1,58.4C7.1,58.4,7.1,58.4,7.1,58.4l0-15.7c1.7,1.2,4.5,2.4,8.5,2.4c0,0,0,0,0.1,0   c0.1,0,0.2,0,0.3,0h36.2v16.2h-6.9v-8.6c0-0.7-0.6-1.3-1.3-1.3c-0.7,0-1.3,0.6-1.3,1.3v8.6H31v-8.6c0-0.7-0.6-1.3-1.3-1.3   c-0.7,0-1.3,0.6-1.3,1.3v8.6H16.8v-8.6c0-0.7-0.6-1.3-1.3-1.3c-0.7,0-1.3,0.6-1.3,1.3v8.5C7.5,61,7.2,58.6,7.1,58.4z M85.4,48   c0,18.9-15.3,34.2-34.2,34.2c-2.8,0-5.6-0.4-8.4-1.2c-8.6-2.5-16.5-8.8-21.4-16.9h32.1c0.7,0,1.3-0.6,1.3-1.3V43.8   c0-0.7-0.6-1.3-1.3-1.3H17.3c0.3-2.2,0.8-4.3,1.5-6.1c0-0.1,0.1-0.1,0.1-0.2c1.4-3.3,3.4-5.9,6.2-7.8c5.9-3.8,15-3.9,25.6-0.3   c0.3,0.1,0.6,0.1,0.9,0c11-3.8,20.4-3.5,26.3,0.7C83,32.5,85.5,39,85.4,48z\"><\/path>\t<path d=\"M68.3,30.1c-0.7-0.1-1.4,0.4-1.5,1.1c-0.1,0.7,0.4,1.4,1.1,1.5c3.4,0.6,5.9,2.6,7.4,6c1.2,2.7,1.3,5.3,1.3,5.3   c0,0.7,0.6,1.3,1.3,1.3c0,0,0,0,0,0c0.7,0,1.3-0.6,1.3-1.4c0-0.1-0.1-3.1-1.4-6.2C75.9,33.5,72.6,30.8,68.3,30.1z\"><\/path>\t<path d=\"M51.2,21.6c0.7,0,1.3-0.6,1.3-1.3V7.5c0-0.7-0.6-1.3-1.3-1.3c-0.7,0-1.3,0.6-1.3,1.3v12.7   C49.9,21,50.5,21.6,51.2,21.6z\"><\/path>\t<path d=\"M56.8,16c0.3,0.1,5,2.6,9.9,2.6c1.8,0,3.6-0.3,5.2-1.2c6.3-3.2,7.6-12.8,7.6-13.2c0.1-0.6-0.2-1.1-0.7-1.4   C78.5,2.7,70-1.8,63.7,1.5c-6.3,3.2-7.6,12.8-7.6,13.2C56,15.2,56.3,15.7,56.8,16z M64.9,3.9c4-2.1,9.7,0.1,11.8,1   c-0.5,2.3-2,8.1-6,10.2c-4,2.1-9.7-0.1-11.8-1C59.4,11.8,60.9,5.9,64.9,3.9z\"><\/path><\/g><\/svg>\t<\/div>\n\t<\/a>\n\t\t<\/div>\n\t\t<div class=\"qodef-m-content\">\n\t\t\t\t\t<h5 class=\"qodef-m-title\">\n\t\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/hero-tonic.com\/es\/products\/\" target=\"_self\">\n\t\t\t\t\t<span class=\"qodef-m-title-text\">Gu\u00eda de suplementos<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t<\/h5>\n\t\t\t<div class=\"qodef-m-text\"><p>\u00bfQui\u00e9n sufre tantos males, a\u00fan se atrever\u00eda a nombrarnos justos?.<\/p><\/div>\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1dbcd23 elementor-section-boxed elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"1dbcd23\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-89359ea\" data-id=\"89359ea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf5f495 elementor-widget__width-initial elementor-widget elementor-widget-qi_addons_for_elementor_icon_with_text\" data-id=\"bf5f495\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_icon_with_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-icon-with-text qodef-layout--top qodef--custom-icon qodef-alignment--center\" >\n\t\t\t<div class=\"qodef-m-icon-wrapper\">\n\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/hero-tonic.com\/es\/peptides\/\" target=\"_self\">\n\t<div class=\"qodef-m-icon-holder\">\n\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 92.6 85.2\" style=\"enable-background:new 0 0 92.6 85.2; stroke:transparent;\" xml:space=\"preserve\"><g>\t<path d=\"M46.3,41.2c0.7,0,1.3-0.6,1.3-1.3v-0.4c0-0.7-0.6-1.3-1.3-1.3s-1.3,0.6-1.3,1.3v0.4   C44.9,40.6,45.5,41.2,46.3,41.2z\"><\/path>\t<path d=\"M79.7,56.8c-1.6-9.1-4-19.1-6.4-26.2c-1.5-4.4-1-9.2,1.3-13.3c2.3-4,4-8.5,4.9-13.3c0.1-0.7-0.3-1.4-1.1-1.6   c-0.7-0.1-1.4,0.3-1.6,1.1c-0.9,4.5-2.4,8.7-4.6,12.5c-2.7,4.7-3.3,10.4-1.5,15.5c1,3,2.1,6.5,3,10.3c-4.1,1.8-8,3.1-11.8,4   l4.4-7.9c0.4-0.7,0.1-1.5-0.5-1.8c-0.7-0.4-1.5-0.1-1.8,0.5l-5.5,10c-9.5,1.8-17.8,1.3-23.9,0.2c-0.1,0-0.3-0.1-0.4-0.1l-5.6-10.1   c-0.4-0.7-1.2-0.9-1.8-0.5c-0.7,0.4-0.9,1.2-0.5,1.8l4.5,8.1c-5.9-1.4-10.1-3.3-11.9-4.1c1-3.8,2-7.4,3-10.4   c1.7-5.1,1.2-10.7-1.5-15.5c-2.2-3.8-3.7-8-4.6-12.5c-0.1-0.7-0.8-1.2-1.6-1.1c-0.7,0.1-1.2,0.8-1.1,1.6c0.9,4.8,2.5,9.3,4.9,13.3   c2.3,4.1,2.8,8.9,1.3,13.3c-2.4,7-4.9,17.1-6.4,26.2c-1.3,7.8-2.6,18.5-1.1,24.8c0.1,0.6,0.7,1,1.3,1c0.1,0,0.2,0,0.3,0   c0.7-0.2,1.2-0.9,1-1.6c-0.4-1.6-0.6-3.6-0.6-6.1c6.1,3.3,12.9,4,17.8,4.1c0,0,0,0,0.1,0c3.4,0,6.2-0.3,8.1-0.6l-0.4,2.7   c-0.1,0.7,0.4,1.4,1.1,1.5c0.1,0,0.1,0,0.2,0c0.7,0,1.2-0.5,1.3-1.1l0.6-4c0.3-0.3,0.4-0.8,0.3-1.2c0-0.1,0-0.2-0.1-0.2l0.8-4.9   c0.9,0.5,1.9,0.8,3,0.8c0,0,0,0,0,0c0.9,0,1.8-0.2,2.6-0.6l0.7,4.8c0,0.1-0.1,0.2-0.1,0.2c-0.1,0.4,0,0.9,0.3,1.2l0.6,4   c0.1,0.7,0.7,1.1,1.3,1.1c0.1,0,0.1,0,0.2,0c0.7-0.1,1.2-0.8,1.1-1.5l-0.4-2.7c1.8,0.3,4.7,0.6,8.1,0.6c0,0,0,0,0.1,0   c4.9,0,11.7-0.8,17.8-4.1c0,2.4-0.2,4.5-0.6,6.1c-0.2,0.7,0.3,1.4,1,1.6c0.1,0,0.2,0,0.3,0c0.6,0,1.2-0.4,1.3-1   C82.4,75.3,81.1,64.6,79.7,56.8z M52.5,75.6l-0.9-6c0.9-0.9,1.8-2.1,2.7-3.5c0.4-0.6,0.2-1.5-0.5-1.8c-0.6-0.4-1.5-0.2-1.8,0.5   c-0.9,1.4-1.7,2.5-2.6,3.3c0,0-0.1,0.1-0.1,0.1c-0.9,0.7-1.8,1.1-2.7,1.1c0,0,0,0,0,0c-2.7,0-5.2-3.2-5.9-4.5   c-0.4-0.6-1.2-0.9-1.8-0.5c-0.6,0.4-0.9,1.2-0.5,1.8c0.1,0.1,1.1,1.8,2.7,3.3l-0.9,6.2c-3.8,0.7-16.5,2.3-26.3-3.7   c0.2-4.1,0.7-9.1,1.7-14.6c0.7-4.2,1.6-8.5,2.6-12.7c2.6,1.2,8.1,3.5,15.9,4.9c4,0.7,8,1,12,1c2.3,0,4.6-0.1,6.8-0.3   c2.1-0.2,4.1-0.5,6.2-0.9c0.1,0,0.2,0,0.3,0c0.3,0,0.5-0.1,0.8-0.2c4.9-1,9.7-2.5,14.4-4.6c1,4.2,1.9,8.6,2.6,12.8   c1,5.6,1.5,10.5,1.7,14.6C69,77.9,56.3,76.3,52.5,75.6z\"><\/path>\t<path d=\"M23.9,9.5c1,0.4,3.3,0.5,6,0.5c4.2,0,9.2-0.3,10.7-0.4c0.3,0,0.5-0.1,0.8-0.3c0.1-0.1,1.9-1.6,3.5-4.8   c0.3-0.7,0-1.5-0.6-1.8c-0.7-0.3-1.5,0-1.8,0.6c-0.9,2-2,3.1-2.5,3.6c-5.5,0.3-13.5,0.6-15,0c-1.6-0.6-2-3.2-2-3.3   c-0.1-0.7-0.8-1.3-1.5-1.2C20.6,2.6,20,3.3,20.1,4C20.2,4.2,20.7,8.3,23.9,9.5z\"><\/path>\t<path d=\"M51.3,9.3c0.2,0.2,0.5,0.3,0.8,0.3c1.4,0.1,6.4,0.4,10.7,0.4c2.6,0,4.9-0.1,6-0.5c3.2-1.2,3.8-5.3,3.8-5.5   c0.1-0.7-0.4-1.4-1.2-1.5c-0.7-0.1-1.4,0.4-1.5,1.2c0,0-0.4,2.7-2,3.3c-1.5,0.5-9.5,0.3-15,0c-0.5-0.5-1.5-1.7-2.5-3.6   c-0.3-0.7-1.1-0.9-1.8-0.6c-0.7,0.3-0.9,1.1-0.6,1.8C49.3,7.7,51.2,9.2,51.3,9.3z\"><\/path>\t<path d=\"M62.1,20.8c0.1-0.7-0.5-1.4-1.2-1.5l-9.2-1c-0.7-0.1-1.4,0.5-1.5,1.2c-0.1,0.7,0.5,1.4,1.2,1.5l9.2,1   c0,0,0.1,0,0.1,0C61.5,22,62,21.5,62.1,20.8z\"><\/path>\t<path d=\"M50.7,27.3c-0.7-0.1-1.4,0.5-1.5,1.2c-0.1,0.7,0.5,1.4,1.2,1.5l9.2,1c0,0,0.1,0,0.1,0c0.7,0,1.3-0.5,1.3-1.2   c0.1-0.7-0.5-1.4-1.2-1.5L50.7,27.3z\"><\/path>\t<path d=\"M31.9,22l9.2-1c0.7-0.1,1.3-0.7,1.2-1.5c-0.1-0.7-0.7-1.3-1.5-1.2l-9.2,1c-0.7,0.1-1.3,0.7-1.2,1.5   c0.1,0.7,0.7,1.2,1.3,1.2C31.8,22,31.9,22,31.9,22z\"><\/path>\t<path d=\"M32.7,31c0,0,0.1,0,0.1,0l9.2-1c0.7-0.1,1.3-0.7,1.2-1.5c-0.1-0.7-0.7-1.3-1.5-1.2l-9.2,1   c-0.7,0.1-1.3,0.7-1.2,1.5C31.4,30.5,32,31,32.7,31z\"><\/path><\/g><\/svg>\t<\/div>\n\t<\/a>\n\t\t<\/div>\n\t\t<div class=\"qodef-m-content\">\n\t\t\t\t\t<h5 class=\"qodef-m-title\">\n\t\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/hero-tonic.com\/es\/peptides\/\" target=\"_self\">\n\t\t\t\t\t<span class=\"qodef-m-title-text\">metodolog\u00eda de entrenamiento<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t<\/h5>\n\t\t\t<div class=\"qodef-m-text\">\u00bfQui\u00e9n sufre tantos males, a\u00fan se atrever\u00eda a nombrarnos justos?.<\/div>\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7d1230b\" data-id=\"7d1230b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c45536 elementor-widget__width-initial elementor-widget elementor-widget-qi_addons_for_elementor_icon_with_text\" data-id=\"4c45536\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_icon_with_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-icon-with-text qodef-layout--top qodef--custom-icon qodef-alignment--center\" >\n\t\t\t<div class=\"qodef-m-icon-wrapper\">\n\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/hero-tonic.com\/es\/peptides\/\" target=\"_self\">\n\t<div class=\"qodef-m-icon-holder\">\n\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" width=\"92.6px\" height=\"85.2px\" viewbox=\"0 0 92.6 85.2\" style=\"enable-background:new 0 0 92.6 85.2;\" xml:space=\"preserve\"><style type=\"text\/css\">\t.st0{}<\/style><path class=\"st0\" d=\"M87.7,56.4l-4.5-4.5c-0.3-0.3-0.7-0.6-1.1-0.8l5-5c1.6-1.6,1.6-4.1,0-5.7l-4.5-4.5c-1.6-1.6-4.1-1.6-5.7,0  L63.5,49.4l-24-24L52.9,12c0.8-0.8,1.2-1.8,1.2-2.9c0-1.1-0.4-2.1-1.2-2.9l-4.5-4.5c-1.6-1.6-4.1-1.6-5.7,0l-5,5  C37.6,6.4,37.3,6,37,5.6l-4.5-4.5c-1.6-1.6-4.1-1.6-5.7,0L21,7l-4.9-4.9c-0.5-0.5-1.4-0.5-1.9,0l-8.5,8.5c-0.5,0.5-0.5,1.4,0,1.9  l4.9,4.9l-5.8,5.8c-1.6,1.6-1.6,4.1,0,5.7l4.5,4.5c0.3,0.3,0.7,0.6,1.1,0.8l-5,5c-1.6,1.6-1.6,4.1,0,5.7l4.5,4.5  c0.8,0.8,1.8,1.2,2.9,1.2s2.1-0.4,2.9-1.2l13.4-13.4l24,24L39.6,73.2c-0.8,0.8-1.2,1.8-1.2,2.9c0,1.1,0.4,2.1,1.2,2.9l4.5,4.5l0,0  c0.8,0.8,1.8,1.2,2.9,1.2c1,0,2.1-0.4,2.9-1.2l5-5c0.2,0.4,0.5,0.8,0.8,1.1L60,84l0,0c0.8,0.8,1.8,1.2,2.9,1.2c1,0,2.1-0.4,2.9-1.2  l5.8-5.8l4.9,4.9c0.3,0.3,0.6,0.4,1,0.4c0.3,0,0.7-0.1,1-0.4l8.5-8.5c0.3-0.3,0.4-0.6,0.4-1c0-0.4-0.1-0.7-0.4-1l-4.9-4.9l5.8-5.8  C89.3,60.5,89.3,57.9,87.7,56.4z M8.6,11.5l6.6-6.6l4,4l-6.6,6.6L8.6,11.5z M13.1,31.4c-0.3,0.3-0.6,0.4-1,0.4c-0.4,0-0.7-0.1-1-0.4  l-4.5-4.5c-0.5-0.5-0.5-1.4,0-1.9L22,9.8c0,0,0,0,0,0c0,0,0,0,0,0l6.7-6.7c0.5-0.5,1.4-0.5,1.9,0l4.5,4.5c0.3,0.3,0.4,0.6,0.4,1  c0,0.4-0.1,0.7-0.4,1l-11,11L13.1,31.4z M13.8,47.4c-0.5,0.5-1.4,0.5-1.9,0l-4.5-4.5c-0.5-0.5-0.5-1.4,0-1.9L26,22.3l11-11  c0,0,0,0,0,0l7.7-7.7c0.5-0.5,1.4-0.5,1.9,0L51,8.2c0.3,0.3,0.4,0.6,0.4,1c0,0.4-0.1,0.7-0.4,1L36.6,24.5c0,0,0,0,0,0c0,0,0,0,0,0  L28.2,33c0,0,0,0,0,0c0,0,0,0,0,0L13.8,47.4z M31,33.9l6.6-6.6l24,24L55,57.9L31,33.9z M47.9,81.5c-0.5,0.5-1.4,0.5-1.9,0l0,0  L41.5,77c-0.3-0.3-0.4-0.6-0.4-1c0-0.4,0.1-0.7,0.4-1l14.4-14.4c0,0,0,0,0,0c0,0,0,0,0,0l8.5-8.5c0,0,0,0,0,0c0,0,0,0,0,0l14.4-14.4  c0.5-0.5,1.4-0.5,1.9,0l4.5,4.5c0.5,0.5,0.5,1.4,0,1.9L66.5,62.9l-11,11l0,0L47.9,81.5z M84,73.7l-6.6,6.6l-4-4l6.6-6.6L84,73.7z   M85.8,60.2l-6.7,6.7c0,0,0,0,0,0c0,0,0,0,0,0l-8.5,8.5c0,0,0,0,0,0c0,0,0,0,0,0l-6.7,6.7c-0.5,0.5-1.4,0.5-1.9,0l-4.5-4.5  c-0.3-0.3-0.4-0.6-0.4-1c0-0.4,0.1-0.7,0.4-1l11-11l11-11c0.3-0.3,0.6-0.4,1-0.4c0.4,0,0.7,0.1,1,0.4l4.5,4.5  C86.3,58.8,86.3,59.6,85.8,60.2z\"><\/path><\/svg>\t<\/div>\n\t<\/a>\n\t\t<\/div>\n\t\t<div class=\"qodef-m-content\">\n\t\t\t\t\t<h5 class=\"qodef-m-title\">\n\t\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/hero-tonic.com\/es\/peptides\/\" target=\"_self\">\n\t\t\t\t\t<span class=\"qodef-m-title-text\">Ejercicios<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t<\/h5>\n\t\t\t<div class=\"qodef-m-text\">\u00bfQui\u00e9n sufre tantos males, a\u00fan se atrever\u00eda a nombrarnos justos?.<\/div>\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-97ca305 elementor-section-full_width elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"97ca305\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-e4ccc22\" data-id=\"e4ccc22\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e194fad elementor-widget elementor-widget-image\" data-id=\"e194fad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"1037\" src=\"https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h-img-2.jpg\" class=\"attachment-full size-full wp-image-2369\" alt=\"p\" srcset=\"https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h-img-2.jpg 1000w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h-img-2-289x300.jpg 289w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h-img-2-987x1024.jpg 987w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h-img-2-768x796.jpg 768w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h-img-2-12x12.jpg 12w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-5331808\" data-id=\"5331808\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50268c8 elementor-widget elementor-widget-heading\" data-id=\"50268c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/hero-tonic.com\/es\/single-class\/\">Pliometr\u00eda bienestar<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e051b04 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"e051b04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"> Nos tenemos nuestro griego, no queremos, explicaremos f\u00e1cilmente \u00e9l. Elige para \u00e9l.<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-a7e799e\" data-id=\"a7e799e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c8601d5 elementor-widget elementor-widget-image\" data-id=\"c8601d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"1037\" src=\"https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h-img-3.jpg\" class=\"attachment-full size-full wp-image-2373\" alt=\"j\" srcset=\"https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h-img-3.jpg 1000w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h-img-3-289x300.jpg 289w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h-img-3-987x1024.jpg 987w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h-img-3-768x796.jpg 768w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h-img-3-12x12.jpg 12w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3556127\" data-id=\"3556127\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cbc5740 elementor-widget elementor-widget-heading\" data-id=\"cbc5740\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/hero-tonic.com\/es\/single-class\/\">bienestar<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b318409 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"b318409\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"> Nos tenemos nuestro griego, no queremos, explicaremos f\u00e1cilmente \u00e9l. Elige para \u00e9l.<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9d10f02 elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"9d10f02\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-05bc6ab\" data-id=\"05bc6ab\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56bcdf9 elementor-widget elementor-widget-heading\" data-id=\"56bcdf9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/hero-tonic.com\/es\/single-class\/\">salud<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1ffb36 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"e1ffb36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"> Nos tenemos nuestro griego, no queremos, explicaremos f\u00e1cilmente \u00e9l. Elige para \u00e9l.<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-70f2ff8\" data-id=\"70f2ff8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb7b20b elementor-widget elementor-widget-image\" data-id=\"cb7b20b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"1037\" src=\"https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h-img-4.jpg\" class=\"attachment-full size-full wp-image-2375\" alt=\"g\" srcset=\"https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h-img-4.jpg 1000w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h-img-4-289x300.jpg 289w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h-img-4-987x1024.jpg 987w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h-img-4-768x796.jpg 768w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h-img-4-12x12.jpg 12w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-71caf99\" data-id=\"71caf99\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-443e5df elementor-widget elementor-widget-heading\" data-id=\"443e5df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/hero-tonic.com\/es\/single-class\/\">rendimiento<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-921a774 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"921a774\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"> Nos tenemos nuestro griego, no queremos, explicaremos f\u00e1cilmente \u00e9l. Elige para \u00e9l.<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-c60cbe2\" data-id=\"c60cbe2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-87e157a elementor-widget elementor-widget-image\" data-id=\"87e157a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1037\" src=\"https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h-img-5.jpg\" class=\"attachment-full size-full wp-image-2376\" alt=\"e\" srcset=\"https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h-img-5.jpg 1000w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h-img-5-289x300.jpg 289w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h-img-5-987x1024.jpg 987w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h-img-5-768x796.jpg 768w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h-img-5-12x12.jpg 12w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-58f7bbb elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"58f7bbb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-eb76ced\" data-id=\"eb76ced\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8eb7a0b elementor-widget elementor-widget-image\" data-id=\"8eb7a0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1092\" src=\"https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h1-team-2.jpg\" class=\"attachment-full size-full wp-image-2417\" alt=\"p\" srcset=\"https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h1-team-2.jpg 1000w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h1-team-2-275x300.jpg 275w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h1-team-2-938x1024.jpg 938w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h1-team-2-768x839.jpg 768w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h1-team-2-11x12.jpg 11w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d38d886\" data-id=\"d38d886\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f712fc elementor-widget elementor-widget-heading\" data-id=\"2f712fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/hero-tonic.com\/es\/single-class\/\">entrenamiento espec\u00edfico para el deporte<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04babe6 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"04babe6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"> Nos tenemos nuestro griego, no queremos, explicaremos f\u00e1cilmente \u00e9l. Elige para \u00e9l.<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5cc5cee\" data-id=\"5cc5cee\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7dccaa4 elementor-widget elementor-widget-image\" data-id=\"7dccaa4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"1037\" src=\"https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h-img-3.jpg\" class=\"attachment-full size-full wp-image-2373\" alt=\"j\" srcset=\"https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h-img-3.jpg 1000w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h-img-3-289x300.jpg 289w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h-img-3-987x1024.jpg 987w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h-img-3-768x796.jpg 768w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h-img-3-12x12.jpg 12w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-43b6a08 elementor-section-full_width elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"43b6a08\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b7d8185\" data-id=\"b7d8185\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a67aaca qodef-elementor-content-grid elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a67aaca\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6865b8e\" data-id=\"6865b8e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a473998 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"a473998\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t<h2 class=\"qodef-m-title\">\n\t\t<span class=\"qodef-e-colored\">PERSONALIZADO<\/span> PLANES<br \/> PARA TODOS\t<\/h2>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bdd85b5\" data-id=\"bdd85b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-939997e elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"939997e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Debet legendos eleifend ei sit. Viderer indoctum an has, mediocrem ex sit, tamquam alterum delicatissimi <span style=\"color: #e90505;\">vim, est\u00e1 en todas partes<\/span> reprenden. Los silenciosos de majestad, y no, y adem\u00e1s, la virtud sirve reformidando, ning\u00fan seguro es no. Molestos justos <span style=\"color: #e90505;\">constituir a ella como.<\/span> Si mi defensa es perfecta, cu sentirme bien, me gusta.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-491c050 qodef-elementor-content-grid elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"491c050\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ee25b1a\" data-id=\"ee25b1a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-251a220 elementor-section-full_width elementor-reverse-tablet elementor-reverse-mobile elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"251a220\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-67b0f18\" data-id=\"67b0f18\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-002a363 elementor-widget-tablet__width-inherit elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"002a363\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--underline qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t<h3 class=\"qodef-m-title\">\n\t\tDesarrollo de la condici\u00f3n f\u00edsica.<br \/> Edificio <span class=\"qodef-e-colored\">confianza.<\/span>\t<\/h3>\n\t\t\t<div class=\"qodef-m-text\"><p>No, al fin, con este cargo, te encontrar\u00eda el c\u00f3nsul Homero. Si a este nuevo argumento que lo encuentra, en qu\u00e9 dolor es apropiado, y con \u00e9l constituido. No todos los dem\u00e1s, en los hombres nombrados la hendidura de la posesi\u00f3n, y, por lo tanto, el recuerdo molesto. Si \u00e9l oye, es una pena, por estas razones.<\/p><\/div>\n\t\t<div class=\"qodef-m-button qodef-qi-clear\">\n\t\t\t<a class=\"qodef-shortcode qodef-m qodef-qi-button qodef-html--link qodef-layout--filled qodef-type--standard qodef-icon--right qodef-hover--icon-move-horizontal-short\" href=\"https:\/\/hero-tonic.com\/es\/about\/\" target=\"_self\">\t\t<span class=\"qodef-m-text\">\u00c9chale un vistazo<\/span>\t\t\t<\/a>\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2fc526d\" data-id=\"2fc526d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d067b53 elementor-widget elementor-widget-video\" data-id=\"d067b53\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/hero-tonic.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/h1-img-12.jpg&quot;,&quot;id&quot;:251,&quot;size&quot;:&quot;&quot;},&quot;video_type&quot;:&quot;vimeo&quot;,&quot;lightbox&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-lightbox\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox=\"{&quot;type&quot;:&quot;video&quot;,&quot;videoType&quot;:&quot;vimeo&quot;,&quot;url&quot;:&quot;https:\\\/\\\/player.vimeo.com\\\/video\\\/441001905?color&amp;autopause=0&amp;loop=0&amp;muted=0&amp;title=0&amp;portrait=0&amp;byline=0#t=&quot;,&quot;autoplay&quot;:&quot;&quot;,&quot;modalOptions&quot;:{&quot;id&quot;:&quot;elementor-lightbox-d067b53&quot;,&quot;entranceAnimation&quot;:&quot;&quot;,&quot;entranceAnimation_tablet&quot;:&quot;&quot;,&quot;entranceAnimation_mobile&quot;:&quot;&quot;,&quot;videoAspectRatio&quot;:&quot;11&quot;}}\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJ0eXBlIjoidmlkZW8iLCJ2aWRlb1R5cGUiOiJ2aW1lbyIsInVybCI6Imh0dHBzOlwvXC9wbGF5ZXIudmltZW8uY29tXC92aWRlb1wvNDQxMDAxOTA1P2NvbG9yJmF1dG9wYXVzZT0wJmxvb3A9MCZtdXRlZD0wJnRpdGxlPTAmcG9ydHJhaXQ9MCZieWxpbmU9MCN0PSIsImF1dG9wbGF5IjoiIiwibW9kYWxPcHRpb25zIjp7ImlkIjoiZWxlbWVudG9yLWxpZ2h0Ym94LWQwNjdiNTMiLCJlbnRyYW5jZUFuaW1hdGlvbiI6IiIsImVudHJhbmNlQW5pbWF0aW9uX3RhYmxldCI6IiIsImVudHJhbmNlQW5pbWF0aW9uX21vYmlsZSI6IiIsInZpZGVvQXNwZWN0UmF0aW8iOiIxMSJ9fQ%3D%3D\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"906\" height=\"863\" src=\"https:\/\/hero-tonic.com\/wp-content\/uploads\/2020\/10\/h1-img-12.jpg\" class=\"attachment-full size-full wp-image-251\" alt=\"a\" srcset=\"https:\/\/hero-tonic.com\/wp-content\/uploads\/2020\/10\/h1-img-12.jpg 906w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2020\/10\/h1-img-12-300x286.jpg 300w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2020\/10\/h1-img-12-768x732.jpg 768w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2020\/10\/h1-img-12-13x12.jpg 13w\" sizes=\"(max-width: 906px) 100vw, 906px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"Reproducir video\" tabindex=\"0\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-play\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M838 162C746 71 633 25 500 25 371 25 258 71 163 162 71 254 25 367 25 500 25 633 71 746 163 837 254 929 367 979 500 979 633 979 746 933 838 837 929 746 975 633 975 500 975 367 929 254 838 162M808 192C892 279 933 379 933 500 933 621 892 725 808 808 725 892 621 938 500 938 379 938 279 896 196 808 113 725 67 621 67 500 67 379 108 279 196 192 279 108 383 62 500 62 621 62 721 108 808 192M438 392V642L642 517 438 392Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ae94515 elementor-section-full_width elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"ae94515\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-dfdcb06\" data-id=\"dfdcb06\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e1b1bf6 elementor-widget__width-initial elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"e1b1bf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t<h3 class=\"qodef-m-title\">\n\t\tcalculadora de IMC tabla\t<\/h3>\n\t\t\t<div class=\"qodef-m-text\"><p>Mejor para ellos, mi voz, que la indulgencia legendaria en. Ellos, por lo tanto, corrompieron el placer. Sus palabras en la regi\u00f3n de la escritura.<\/p><\/div>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bd8407 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"3bd8407\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Tasa Metab\u00f3lica Basal (BMR) \/ \u00cdndice de Masa Corporal (IMC)<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ef0736 elementor-widget elementor-widget-spacer\" data-id=\"1ef0736\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4f26ea8 elementor-section-boxed elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"4f26ea8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-91ccfe2\" data-id=\"91ccfe2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a6c39f7 elementor-widget elementor-widget-heading\" data-id=\"a6c39f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">IMC<\/h5>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-670c3b7\" data-id=\"670c3b7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-253b051 elementor-widget elementor-widget-heading\" data-id=\"253b051\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">estado de peso<\/h5>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3af65f2 elementor-section-boxed elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"3af65f2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0d1e1ff\" data-id=\"0d1e1ff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3584955 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"3584955\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Por debajo de 18.5\n18.5 - 24.9\n25.0 - 29.9\n<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-551f891 elementor-widget elementor-widget-heading\" data-id=\"551f891\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">30.0 - y superior\n<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-17b81a4\" data-id=\"17b81a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bba8818 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"bba8818\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Bajo peso\nSaludable\nSobrepeso\nObeso\n<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b77af98\" data-id=\"b77af98\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e2339ee elementor-widget__width-initial elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"e2339ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t<h3 class=\"qodef-m-title\">\n\t\tcalcular tu <span class=\"qodef-e-colored\">IMC<\/span>\t<\/h3>\n\t\t\t<div class=\"qodef-m-text\"><p>La ense\u00f1anza de estos, que est\u00e1 en todos los adornos. Han liberado a los pr\u00edncipes de la ley y, con la cosm\u00e9tica, les importa el dilema emp\u00edrico, con me la conclusi\u00f3n de la acusaci\u00f3n. Si la \u00e9lite es equitativa, y en m\u00ed la alabanza de la partida.<\/p><\/div>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c86da69 elementor-widget elementor-widget-spacer\" data-id=\"c86da69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-125334b elementor-widget__width-initial elementor-widget elementor-widget-qi_addons_for_elementor_contact_form_7\" data-id=\"125334b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_contact_form_7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-contact-form-7\">\n\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f932-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"932\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/pages\/6#wpcf7-f932-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/es\/wp-json\/wp\/v2\/pages\/6#wpcf7-f932-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"932\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f932-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"qodef-grid qodef-layout--columns qodef-col-num--2 qodef-responsive--predefined qodef-gutter--small\">\n<div class=\"qodef-grid-inner clear\">\n\n<div class=\"qodef-grid-item\">\n<span class=\"wpcf7-form-control-wrap\" data-name=\"height\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Altura\/cm\" value=\"\" type=\"text\" name=\"height\" \/><\/span>\n<\/div>\n\n<div class=\"qodef-grid-item\">\n<span class=\"wpcf7-form-control-wrap\" data-name=\"weight\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Peso\/kg\" value=\"\" type=\"text\" name=\"weight\" \/><\/span>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"qodef-grid qodef-layout--columns qodef-col-num--2 qodef-responsive--predefined qodef-gutter--small\">\n<div class=\"qodef-grid-inner clear\">\n\n<div class=\"qodef-grid-item\">\n<span class=\"wpcf7-form-control-wrap\" data-name=\"age\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Edad\" value=\"\" type=\"text\" name=\"age\" \/><\/span>\n<\/div>\n\n<div class=\"qodef-grid-item\">\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sex\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Sexo\" value=\"\" type=\"text\" name=\"sex\" \/><\/span>\n<\/div>\n<\/div>\n<\/div>\n\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Selecciona un factor de actividad:\" value=\"\" type=\"text\" name=\"your-message\" \/><\/span>\n\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Calcular\" \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f9a779 elementor-section-full_width elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"6f9a779\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-ccf55f8\" data-id=\"ccf55f8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c395bf2 elementor-widget elementor-widget-qi_addons_for_elementor_image_gallery\" data-id=\"c395bf2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_image_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-image-gallery qodef-qi-grid qodef-layout--qi-columns qodef-col-num--1 qodef-responsive--predefined\">\n\t<div class=\"qodef-grid-inner\">\n\t\t<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1092\" src=\"https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h1-team-1.jpg\" class=\"attachment-full size-full\" alt=\"p\" srcset=\"https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h1-team-1.jpg 1000w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h1-team-1-275x300.jpg 275w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h1-team-1-938x1024.jpg 938w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h1-team-1-768x839.jpg 768w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h1-team-1-11x12.jpg 11w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d274a14 elementor-widget elementor-widget-qi_addons_for_elementor_team_member\" data-id=\"d274a14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_team_member.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-team-member qodef-item-layout--info-below\">\n\t<div class=\"qodef-m-inner\">\n\t\t<div class=\"qodef-m-image\">\n\t\t\t\t\t<\/div>\n\t\t<div class=\"qodef-m-content\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"qodef-m-title\">\n\t\tJulie Williams\t<\/h4>\n\t\t\t\t\t<p class=\"qodef-m-role\">N\u00facleo, Entrenador personal<\/p>\n\t\t\t\t<div class=\"qodef-m-social-icons\">\n\t\t\t\t\t\t\t<a class=\"qodef-e-social-icon-link\" itemprop=\"url\" href=\"https:\/\/www.instagram.com\" target=\"_blank\">\n\t\t\t\t\t\t\t\t<span class=\"qodef-e-social-icon\">\n\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 19.2 18\" style=\"enable-background:new 0 0 19.2 18; stroke:transparent;\" xml:space=\"preserve\"><g>\t<path d=\"M17.5,9c0,1.5,0,2.6-0.1,3.3s-0.1,1.2-0.3,1.7c-0.2,0.6-0.5,1.1-1,1.5c-0.4,0.4-0.9,0.8-1.5,1   c-0.5,0.2-1.1,0.3-1.7,0.3s-1.8,0.1-3.3,0.1c-1.5,0-2.6,0-3.3-0.1s-1.2-0.1-1.7-0.3C4,16.3,3.5,16,3,15.6c-0.4-0.4-0.8-0.9-1-1.5   c-0.2-0.5-0.3-1.1-0.3-1.7S1.7,10.5,1.7,9c0-1.5,0-2.6,0.1-3.3S1.9,4.5,2.1,4c0.2-0.6,0.5-1.1,1-1.5C3.5,2,4,1.7,4.6,1.5   c0.5-0.2,1.1-0.3,1.7-0.3s1.8-0.1,3.3-0.1c1.5,0,2.6,0,3.3,0.1s1.2,0.1,1.7,0.3c0.6,0.2,1.1,0.5,1.5,1c0.4,0.4,0.8,0.9,1,1.5   c0.2,0.5,0.3,1.1,0.3,1.8C17.5,6.4,17.5,7.5,17.5,9z M16,11.7c0-0.5,0-1.2,0-2.2V8.4c0-1,0-1.7,0-2.2c0-0.9-0.1-1.5-0.3-1.9   c-0.3-0.7-0.8-1.2-1.5-1.5c-0.4-0.1-1-0.2-1.9-0.3c-0.5,0-1.2,0-2.2,0H9c-0.9,0-1.7,0-2.2,0C6,2.6,5.4,2.7,5,2.8   C4.2,3.1,3.7,3.6,3.4,4.4c-0.1,0.4-0.2,1-0.3,1.9c0,0.5,0,1.2,0,2.2v1.1c0,0.9,0,1.7,0,2.2c0,0.9,0.1,1.5,0.3,1.9   c0.3,0.7,0.8,1.2,1.5,1.5c0.4,0.1,1,0.2,1.9,0.3c0.5,0,1.2,0,2.2,0h1.1c1,0,1.7,0,2.2,0c0.9,0,1.5-0.1,1.9-0.3   c0.7-0.3,1.2-0.8,1.5-1.5C15.9,13.2,16,12.6,16,11.7z M11.6,5.5c0.6,0.4,1.1,0.9,1.5,1.5c0.4,0.6,0.5,1.3,0.5,2   c0,0.7-0.2,1.4-0.5,2c-0.4,0.6-0.9,1.1-1.5,1.5c-0.6,0.4-1.3,0.5-2,0.5c-0.7,0-1.4-0.2-2-0.5C7,12.1,6.5,11.6,6.1,11   c-0.4-0.6-0.5-1.3-0.5-2c0-0.7,0.2-1.4,0.5-2C6.5,6.4,7,5.9,7.6,5.5C8.2,5.1,8.9,5,9.6,5C10.3,5,11,5.1,11.6,5.5z M11.5,10.9   c0.5-0.5,0.8-1.1,0.8-1.9c0-0.7-0.3-1.3-0.8-1.9c-0.5-0.5-1.1-0.8-1.9-0.8c-0.7,0-1.3,0.3-1.9,0.8C7.2,7.7,7,8.3,7,9   c0,0.7,0.3,1.3,0.8,1.9c0.5,0.5,1.1,0.8,1.9,0.8C10.3,11.6,10.9,11.4,11.5,10.9z M14.5,4.1c-0.2-0.2-0.4-0.3-0.7-0.3   c-0.3,0-0.5,0.1-0.7,0.3c-0.2,0.2-0.3,0.4-0.3,0.7c0,0.3,0.1,0.5,0.3,0.7c0.2,0.2,0.4,0.3,0.7,0.3c0.3,0,0.5-0.1,0.7-0.3   c0.2-0.2,0.3-0.4,0.3-0.7C14.8,4.5,14.7,4.3,14.5,4.1z\"><\/path><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<a class=\"qodef-e-social-icon-link\" itemprop=\"url\" href=\"https:\/\/www.facebook.com\/\" target=\"_blank\">\n\t\t\t\t\t\t\t\t<span class=\"qodef-e-social-icon\">\n\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 19.2 18\" style=\"enable-background:new 0 0 19.2 18; stroke:transparent;\" xml:space=\"preserve\"><g>\t<path class=\"st0\" d=\"M7.7,18V9.9H5V6.8h2.7V4.2c0-1.3,0.4-2.4,1.1-3.1c0.8-0.7,1.7-1.1,3-1.1c1,0,1.8,0,2.5,0.1V3h-1.7   c-0.6,0-1.1,0.1-1.3,0.4C11.1,3.6,11,4,11,4.5v2.2h3l-0.4,3.2H11V18H7.7z\"><\/path><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-87408d3\" data-id=\"87408d3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-220d632 elementor-widget elementor-widget-qi_addons_for_elementor_image_gallery\" data-id=\"220d632\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_image_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-image-gallery qodef-qi-grid qodef-layout--qi-columns qodef-col-num--1 qodef-responsive--predefined\">\n\t<div class=\"qodef-grid-inner\">\n\t\t<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1092\" src=\"https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h1-team-2.jpg\" class=\"attachment-full size-full\" alt=\"p\" srcset=\"https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h1-team-2.jpg 1000w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h1-team-2-275x300.jpg 275w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h1-team-2-938x1024.jpg 938w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h1-team-2-768x839.jpg 768w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h1-team-2-11x12.jpg 11w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ec54d1 elementor-widget elementor-widget-qi_addons_for_elementor_team_member\" data-id=\"0ec54d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_team_member.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-team-member qodef-item-layout--info-below\">\n\t<div class=\"qodef-m-inner\">\n\t\t<div class=\"qodef-m-image\">\n\t\t\t\t\t<\/div>\n\t\t<div class=\"qodef-m-content\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"qodef-m-title\">\n\t\tFrank Lyman\t<\/h4>\n\t\t\t\t\t<p class=\"qodef-m-role\">Entrenador de culturismo<\/p>\n\t\t\t\t<div class=\"qodef-m-social-icons\">\n\t\t\t\t\t\t\t<a class=\"qodef-e-social-icon-link\" itemprop=\"url\" href=\"https:\/\/www.instagram.com\/\" target=\"_blank\">\n\t\t\t\t\t\t\t\t<span class=\"qodef-e-social-icon\">\n\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 19.2 18\" style=\"enable-background:new 0 0 19.2 18; stroke:transparent;\" xml:space=\"preserve\"><g>\t<path d=\"M17.5,9c0,1.5,0,2.6-0.1,3.3s-0.1,1.2-0.3,1.7c-0.2,0.6-0.5,1.1-1,1.5c-0.4,0.4-0.9,0.8-1.5,1   c-0.5,0.2-1.1,0.3-1.7,0.3s-1.8,0.1-3.3,0.1c-1.5,0-2.6,0-3.3-0.1s-1.2-0.1-1.7-0.3C4,16.3,3.5,16,3,15.6c-0.4-0.4-0.8-0.9-1-1.5   c-0.2-0.5-0.3-1.1-0.3-1.7S1.7,10.5,1.7,9c0-1.5,0-2.6,0.1-3.3S1.9,4.5,2.1,4c0.2-0.6,0.5-1.1,1-1.5C3.5,2,4,1.7,4.6,1.5   c0.5-0.2,1.1-0.3,1.7-0.3s1.8-0.1,3.3-0.1c1.5,0,2.6,0,3.3,0.1s1.2,0.1,1.7,0.3c0.6,0.2,1.1,0.5,1.5,1c0.4,0.4,0.8,0.9,1,1.5   c0.2,0.5,0.3,1.1,0.3,1.8C17.5,6.4,17.5,7.5,17.5,9z M16,11.7c0-0.5,0-1.2,0-2.2V8.4c0-1,0-1.7,0-2.2c0-0.9-0.1-1.5-0.3-1.9   c-0.3-0.7-0.8-1.2-1.5-1.5c-0.4-0.1-1-0.2-1.9-0.3c-0.5,0-1.2,0-2.2,0H9c-0.9,0-1.7,0-2.2,0C6,2.6,5.4,2.7,5,2.8   C4.2,3.1,3.7,3.6,3.4,4.4c-0.1,0.4-0.2,1-0.3,1.9c0,0.5,0,1.2,0,2.2v1.1c0,0.9,0,1.7,0,2.2c0,0.9,0.1,1.5,0.3,1.9   c0.3,0.7,0.8,1.2,1.5,1.5c0.4,0.1,1,0.2,1.9,0.3c0.5,0,1.2,0,2.2,0h1.1c1,0,1.7,0,2.2,0c0.9,0,1.5-0.1,1.9-0.3   c0.7-0.3,1.2-0.8,1.5-1.5C15.9,13.2,16,12.6,16,11.7z M11.6,5.5c0.6,0.4,1.1,0.9,1.5,1.5c0.4,0.6,0.5,1.3,0.5,2   c0,0.7-0.2,1.4-0.5,2c-0.4,0.6-0.9,1.1-1.5,1.5c-0.6,0.4-1.3,0.5-2,0.5c-0.7,0-1.4-0.2-2-0.5C7,12.1,6.5,11.6,6.1,11   c-0.4-0.6-0.5-1.3-0.5-2c0-0.7,0.2-1.4,0.5-2C6.5,6.4,7,5.9,7.6,5.5C8.2,5.1,8.9,5,9.6,5C10.3,5,11,5.1,11.6,5.5z M11.5,10.9   c0.5-0.5,0.8-1.1,0.8-1.9c0-0.7-0.3-1.3-0.8-1.9c-0.5-0.5-1.1-0.8-1.9-0.8c-0.7,0-1.3,0.3-1.9,0.8C7.2,7.7,7,8.3,7,9   c0,0.7,0.3,1.3,0.8,1.9c0.5,0.5,1.1,0.8,1.9,0.8C10.3,11.6,10.9,11.4,11.5,10.9z M14.5,4.1c-0.2-0.2-0.4-0.3-0.7-0.3   c-0.3,0-0.5,0.1-0.7,0.3c-0.2,0.2-0.3,0.4-0.3,0.7c0,0.3,0.1,0.5,0.3,0.7c0.2,0.2,0.4,0.3,0.7,0.3c0.3,0,0.5-0.1,0.7-0.3   c0.2-0.2,0.3-0.4,0.3-0.7C14.8,4.5,14.7,4.3,14.5,4.1z\"><\/path><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<a class=\"qodef-e-social-icon-link\" itemprop=\"url\" href=\"https:\/\/www.facebook.com\/\" target=\"_blank\">\n\t\t\t\t\t\t\t\t<span class=\"qodef-e-social-icon\">\n\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 19.2 18\" style=\"enable-background:new 0 0 19.2 18; stroke:transparent;\" xml:space=\"preserve\"><g>\t<path class=\"st0\" d=\"M7.7,18V9.9H5V6.8h2.7V4.2c0-1.3,0.4-2.4,1.1-3.1c0.8-0.7,1.7-1.1,3-1.1c1,0,1.8,0,2.5,0.1V3h-1.7   c-0.6,0-1.1,0.1-1.3,0.4C11.1,3.6,11,4,11,4.5v2.2h3l-0.4,3.2H11V18H7.7z\"><\/path><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-44466c8\" data-id=\"44466c8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5dca99 elementor-widget elementor-widget-qi_addons_for_elementor_image_gallery\" data-id=\"b5dca99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_image_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-image-gallery qodef-qi-grid qodef-layout--qi-columns qodef-col-num--1 qodef-responsive--predefined\">\n\t<div class=\"qodef-grid-inner\">\n\t\t<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1092\" src=\"https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h1-team-3.jpg\" class=\"attachment-full size-full\" alt=\"p\" srcset=\"https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h1-team-3.jpg 1000w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h1-team-3-275x300.jpg 275w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h1-team-3-938x1024.jpg 938w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h1-team-3-768x839.jpg 768w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h1-team-3-11x12.jpg 11w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7db464 elementor-widget elementor-widget-qi_addons_for_elementor_team_member\" data-id=\"e7db464\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_team_member.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-team-member qodef-item-layout--info-below\">\n\t<div class=\"qodef-m-inner\">\n\t\t<div class=\"qodef-m-image\">\n\t\t\t\t\t<\/div>\n\t\t<div class=\"qodef-m-content\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"qodef-m-title\">\n\t\tMolly Peters\t<\/h4>\n\t\t\t\t\t<p class=\"qodef-m-role\">Cardio y Acondicionamiento<\/p>\n\t\t\t\t<div class=\"qodef-m-social-icons\">\n\t\t\t\t\t\t\t<a class=\"qodef-e-social-icon-link\" itemprop=\"url\" href=\"https:\/\/www.instagram.com\/\" target=\"_blank\">\n\t\t\t\t\t\t\t\t<span class=\"qodef-e-social-icon\">\n\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 19.2 18\" style=\"enable-background:new 0 0 19.2 18; stroke:transparent;\" xml:space=\"preserve\"><g>\t<path d=\"M17.5,9c0,1.5,0,2.6-0.1,3.3s-0.1,1.2-0.3,1.7c-0.2,0.6-0.5,1.1-1,1.5c-0.4,0.4-0.9,0.8-1.5,1   c-0.5,0.2-1.1,0.3-1.7,0.3s-1.8,0.1-3.3,0.1c-1.5,0-2.6,0-3.3-0.1s-1.2-0.1-1.7-0.3C4,16.3,3.5,16,3,15.6c-0.4-0.4-0.8-0.9-1-1.5   c-0.2-0.5-0.3-1.1-0.3-1.7S1.7,10.5,1.7,9c0-1.5,0-2.6,0.1-3.3S1.9,4.5,2.1,4c0.2-0.6,0.5-1.1,1-1.5C3.5,2,4,1.7,4.6,1.5   c0.5-0.2,1.1-0.3,1.7-0.3s1.8-0.1,3.3-0.1c1.5,0,2.6,0,3.3,0.1s1.2,0.1,1.7,0.3c0.6,0.2,1.1,0.5,1.5,1c0.4,0.4,0.8,0.9,1,1.5   c0.2,0.5,0.3,1.1,0.3,1.8C17.5,6.4,17.5,7.5,17.5,9z M16,11.7c0-0.5,0-1.2,0-2.2V8.4c0-1,0-1.7,0-2.2c0-0.9-0.1-1.5-0.3-1.9   c-0.3-0.7-0.8-1.2-1.5-1.5c-0.4-0.1-1-0.2-1.9-0.3c-0.5,0-1.2,0-2.2,0H9c-0.9,0-1.7,0-2.2,0C6,2.6,5.4,2.7,5,2.8   C4.2,3.1,3.7,3.6,3.4,4.4c-0.1,0.4-0.2,1-0.3,1.9c0,0.5,0,1.2,0,2.2v1.1c0,0.9,0,1.7,0,2.2c0,0.9,0.1,1.5,0.3,1.9   c0.3,0.7,0.8,1.2,1.5,1.5c0.4,0.1,1,0.2,1.9,0.3c0.5,0,1.2,0,2.2,0h1.1c1,0,1.7,0,2.2,0c0.9,0,1.5-0.1,1.9-0.3   c0.7-0.3,1.2-0.8,1.5-1.5C15.9,13.2,16,12.6,16,11.7z M11.6,5.5c0.6,0.4,1.1,0.9,1.5,1.5c0.4,0.6,0.5,1.3,0.5,2   c0,0.7-0.2,1.4-0.5,2c-0.4,0.6-0.9,1.1-1.5,1.5c-0.6,0.4-1.3,0.5-2,0.5c-0.7,0-1.4-0.2-2-0.5C7,12.1,6.5,11.6,6.1,11   c-0.4-0.6-0.5-1.3-0.5-2c0-0.7,0.2-1.4,0.5-2C6.5,6.4,7,5.9,7.6,5.5C8.2,5.1,8.9,5,9.6,5C10.3,5,11,5.1,11.6,5.5z M11.5,10.9   c0.5-0.5,0.8-1.1,0.8-1.9c0-0.7-0.3-1.3-0.8-1.9c-0.5-0.5-1.1-0.8-1.9-0.8c-0.7,0-1.3,0.3-1.9,0.8C7.2,7.7,7,8.3,7,9   c0,0.7,0.3,1.3,0.8,1.9c0.5,0.5,1.1,0.8,1.9,0.8C10.3,11.6,10.9,11.4,11.5,10.9z M14.5,4.1c-0.2-0.2-0.4-0.3-0.7-0.3   c-0.3,0-0.5,0.1-0.7,0.3c-0.2,0.2-0.3,0.4-0.3,0.7c0,0.3,0.1,0.5,0.3,0.7c0.2,0.2,0.4,0.3,0.7,0.3c0.3,0,0.5-0.1,0.7-0.3   c0.2-0.2,0.3-0.4,0.3-0.7C14.8,4.5,14.7,4.3,14.5,4.1z\"><\/path><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<a class=\"qodef-e-social-icon-link\" itemprop=\"url\" href=\"https:\/\/www.facebook.com\/\" target=\"_blank\">\n\t\t\t\t\t\t\t\t<span class=\"qodef-e-social-icon\">\n\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 19.2 18\" style=\"enable-background:new 0 0 19.2 18; stroke:transparent;\" xml:space=\"preserve\"><g>\t<path class=\"st0\" d=\"M7.7,18V9.9H5V6.8h2.7V4.2c0-1.3,0.4-2.4,1.1-3.1c0.8-0.7,1.7-1.1,3-1.1c1,0,1.8,0,2.5,0.1V3h-1.7   c-0.6,0-1.1,0.1-1.3,0.4C11.1,3.6,11,4,11,4.5v2.2h3l-0.4,3.2H11V18H7.7z\"><\/path><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-4b6e816\" data-id=\"4b6e816\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c110f6 elementor-widget elementor-widget-qi_addons_for_elementor_image_gallery\" data-id=\"1c110f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_image_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-image-gallery qodef-qi-grid qodef-layout--qi-columns qodef-col-num--1 qodef-responsive--predefined\">\n\t<div class=\"qodef-grid-inner\">\n\t\t<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1092\" src=\"https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h1-team-4.jpg\" class=\"attachment-full size-full\" alt=\"y\" srcset=\"https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h1-team-4.jpg 1000w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h1-team-4-275x300.jpg 275w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h1-team-4-938x1024.jpg 938w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h1-team-4-768x839.jpg 768w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2021\/06\/h1-team-4-11x12.jpg 11w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1988d9 elementor-widget elementor-widget-qi_addons_for_elementor_team_member\" data-id=\"f1988d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_team_member.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-team-member qodef-item-layout--info-below\">\n\t<div class=\"qodef-m-inner\">\n\t\t<div class=\"qodef-m-image\">\n\t\t\t\t\t<\/div>\n\t\t<div class=\"qodef-m-content\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"qodef-m-title\">\n\t\tWarren Bower\t<\/h4>\n\t\t\t\t\t<p class=\"qodef-m-role\">Instructor de yoga<\/p>\n\t\t\t\t<div class=\"qodef-m-social-icons\">\n\t\t\t\t\t\t\t<a class=\"qodef-e-social-icon-link\" itemprop=\"url\" href=\"https:\/\/www.instagram.com\/\" target=\"_blank\">\n\t\t\t\t\t\t\t\t<span class=\"qodef-e-social-icon\">\n\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 19.2 18\" style=\"enable-background:new 0 0 19.2 18; stroke:transparent;\" xml:space=\"preserve\"><g>\t<path d=\"M17.5,9c0,1.5,0,2.6-0.1,3.3s-0.1,1.2-0.3,1.7c-0.2,0.6-0.5,1.1-1,1.5c-0.4,0.4-0.9,0.8-1.5,1   c-0.5,0.2-1.1,0.3-1.7,0.3s-1.8,0.1-3.3,0.1c-1.5,0-2.6,0-3.3-0.1s-1.2-0.1-1.7-0.3C4,16.3,3.5,16,3,15.6c-0.4-0.4-0.8-0.9-1-1.5   c-0.2-0.5-0.3-1.1-0.3-1.7S1.7,10.5,1.7,9c0-1.5,0-2.6,0.1-3.3S1.9,4.5,2.1,4c0.2-0.6,0.5-1.1,1-1.5C3.5,2,4,1.7,4.6,1.5   c0.5-0.2,1.1-0.3,1.7-0.3s1.8-0.1,3.3-0.1c1.5,0,2.6,0,3.3,0.1s1.2,0.1,1.7,0.3c0.6,0.2,1.1,0.5,1.5,1c0.4,0.4,0.8,0.9,1,1.5   c0.2,0.5,0.3,1.1,0.3,1.8C17.5,6.4,17.5,7.5,17.5,9z M16,11.7c0-0.5,0-1.2,0-2.2V8.4c0-1,0-1.7,0-2.2c0-0.9-0.1-1.5-0.3-1.9   c-0.3-0.7-0.8-1.2-1.5-1.5c-0.4-0.1-1-0.2-1.9-0.3c-0.5,0-1.2,0-2.2,0H9c-0.9,0-1.7,0-2.2,0C6,2.6,5.4,2.7,5,2.8   C4.2,3.1,3.7,3.6,3.4,4.4c-0.1,0.4-0.2,1-0.3,1.9c0,0.5,0,1.2,0,2.2v1.1c0,0.9,0,1.7,0,2.2c0,0.9,0.1,1.5,0.3,1.9   c0.3,0.7,0.8,1.2,1.5,1.5c0.4,0.1,1,0.2,1.9,0.3c0.5,0,1.2,0,2.2,0h1.1c1,0,1.7,0,2.2,0c0.9,0,1.5-0.1,1.9-0.3   c0.7-0.3,1.2-0.8,1.5-1.5C15.9,13.2,16,12.6,16,11.7z M11.6,5.5c0.6,0.4,1.1,0.9,1.5,1.5c0.4,0.6,0.5,1.3,0.5,2   c0,0.7-0.2,1.4-0.5,2c-0.4,0.6-0.9,1.1-1.5,1.5c-0.6,0.4-1.3,0.5-2,0.5c-0.7,0-1.4-0.2-2-0.5C7,12.1,6.5,11.6,6.1,11   c-0.4-0.6-0.5-1.3-0.5-2c0-0.7,0.2-1.4,0.5-2C6.5,6.4,7,5.9,7.6,5.5C8.2,5.1,8.9,5,9.6,5C10.3,5,11,5.1,11.6,5.5z M11.5,10.9   c0.5-0.5,0.8-1.1,0.8-1.9c0-0.7-0.3-1.3-0.8-1.9c-0.5-0.5-1.1-0.8-1.9-0.8c-0.7,0-1.3,0.3-1.9,0.8C7.2,7.7,7,8.3,7,9   c0,0.7,0.3,1.3,0.8,1.9c0.5,0.5,1.1,0.8,1.9,0.8C10.3,11.6,10.9,11.4,11.5,10.9z M14.5,4.1c-0.2-0.2-0.4-0.3-0.7-0.3   c-0.3,0-0.5,0.1-0.7,0.3c-0.2,0.2-0.3,0.4-0.3,0.7c0,0.3,0.1,0.5,0.3,0.7c0.2,0.2,0.4,0.3,0.7,0.3c0.3,0,0.5-0.1,0.7-0.3   c0.2-0.2,0.3-0.4,0.3-0.7C14.8,4.5,14.7,4.3,14.5,4.1z\"><\/path><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<a class=\"qodef-e-social-icon-link\" itemprop=\"url\" href=\"https:\/\/www.facebook.com\/\" target=\"_blank\">\n\t\t\t\t\t\t\t\t<span class=\"qodef-e-social-icon\">\n\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 19.2 18\" style=\"enable-background:new 0 0 19.2 18; stroke:transparent;\" xml:space=\"preserve\"><g>\t<path class=\"st0\" d=\"M7.7,18V9.9H5V6.8h2.7V4.2c0-1.3,0.4-2.4,1.1-3.1c0.8-0.7,1.7-1.1,3-1.1c1,0,1.8,0,2.5,0.1V3h-1.7   c-0.6,0-1.1,0.1-1.3,0.4C11.1,3.6,11,4,11,4.5v2.2h3l-0.4,3.2H11V18H7.7z\"><\/path><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-95783f0 elementor-section-full_width elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"95783f0\" data-element_type=\"section\" data-e-type=\"section\" id=\"prices\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8432ef4\" data-id=\"8432ef4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-87f1f52 qodef-elementor-content-grid elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"87f1f52\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-805339c\" data-id=\"805339c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c936b8b elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"c936b8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t<h2 class=\"qodef-m-title\">\n\t\telige tu<br \/> <span class=\"qodef-e-colored\">Precios<\/span> plan\t<\/h2>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e7011dc\" data-id=\"e7011dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe9f16f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"fe9f16f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Debe <span style=\"color: #e90505;\">leyenda de eleifend<\/span> Ah\u00ed est\u00e1. Veo una doctrina sobre esto, una moderaci\u00f3n en esto, y a los m\u00e1s delicados como si fueran uno con \u00e9l, y \u00e9l est\u00e1 en todas partes de forma reprehensible. Tacimates majestuosos ni siquiera, y si la virtud de las reformificaciones es \u00fatil, no hay nada que lo haga. Es suficiente para molestos constituyentes. Que no haya contiendas perfectas en \u00e9l. <span style=\"color: #e90505;\">Para ser honesto, solo siento mis cosas<\/span> Encontrar apenas si los animales latinos fueron consultados, y en los deberes de los pesos de los l\u00edderes, y con esto el di\u00e1metro de saludo.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-30caeae elementor-section-full_width qodef-elementor-content-grid elementor-section-height-default elementor-section-height-default\" data-id=\"30caeae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2b22a1f\" data-id=\"2b22a1f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b2e6f5 elementor-widget elementor-widget-qi_addons_for_elementor_pricing_table\" data-id=\"5b2e6f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_pricing_table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-pricing-table qodef-layout--minimal qodef-status--regular qodef-list-type--none qodef-label-type--badge qodef-period--side\">\n\t<div class=\"qodef-m-inner\">\n\t\t\t<div class=\"qodef-m-price\">\n\t\t<div class=\"qodef-m-price-wrapper qodef-h1\">\n\t\t\t\t\t\t\t<span class=\"qodef-m-price-currency\">$<\/span>\n\t\t\t\t\t\t<span class=\"qodef-m-price-value\">35<\/span>\n\t\t<\/div>\n\t\t\t\t\t<span class=\"qodef-m-price-period\">Por d\u00eda<\/span>\n\t\t\t<\/div>\n\t\t\t<h4 class=\"qodef-m-title\">\n\t\tboleto diario\t<\/h4>\n\t\t\t\t\t<ol class=\"qodef-m-content\">\n\t\t\t\t\t<li class=\"qodef-e-item\">\n\t\t\t\t\t\t\t\t<span class=\"qodef-e-text\">Sin que perpet.<\/span>\n\t\t\t<\/li>\n\t\t\t<\/ol>\n\t\t\t<div class=\"qodef-m-button qodef-qi-clear\">\n\t\t\t<a class=\"qodef-shortcode qodef-m qodef-qi-button qodef-html--link qodef-layout--filled qodef-type--standard qodef-icon--right qodef-hover--icon-move-horizontal-short\" href=\"https:\/\/hero-tonic.com\/es\/contact\/\" target=\"_self\">\t\t<span class=\"qodef-m-text\">Leer m\u00e1s<\/span>\t\t\t<\/a>\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1de98a0\" data-id=\"1de98a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-faefc6f elementor-widget elementor-widget-qi_addons_for_elementor_pricing_table\" data-id=\"faefc6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_pricing_table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-pricing-table qodef-layout--minimal qodef-status--featured qodef-list-type--none qodef-label-type--badge qodef-period--side\">\n\t<div class=\"qodef-m-inner\">\n\t\t\t<div class=\"qodef-m-price\">\n\t\t<div class=\"qodef-m-price-wrapper qodef-h1\">\n\t\t\t\t\t\t\t<span class=\"qodef-m-price-currency\">$<\/span>\n\t\t\t\t\t\t<span class=\"qodef-m-price-value\">135<\/span>\n\t\t<\/div>\n\t\t\t\t\t<span class=\"qodef-m-price-period\">Por mes<\/span>\n\t\t\t<\/div>\n\t\t\t<h4 class=\"qodef-m-title\">\n\t\tMembres\u00eda de 3 meses\t<\/h4>\n\t\t\t\t\t<ol class=\"qodef-m-content\">\n\t\t\t\t\t<li class=\"qodef-e-item\">\n\t\t\t\t\t\t\t\t<span class=\"qodef-e-text\">Sin que perpet.<\/span>\n\t\t\t<\/li>\n\t\t\t<\/ol>\n\t\t\t<div class=\"qodef-m-button qodef-qi-clear\">\n\t\t\t<a class=\"qodef-shortcode qodef-m qodef-qi-button qodef-html--link qodef-layout--filled qodef-type--standard qodef-icon--right qodef-hover--icon-move-horizontal-short\" href=\"https:\/\/hero-tonic.com\/es\/contact\/\" target=\"_self\">\t\t<span class=\"qodef-m-text\">Leer m\u00e1s<\/span>\t\t\t<\/a>\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-eaad4db\" data-id=\"eaad4db\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36cde54 elementor-widget elementor-widget-qi_addons_for_elementor_pricing_table\" data-id=\"36cde54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_pricing_table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-pricing-table qodef-layout--minimal qodef-status--regular qodef-list-type--none qodef-label-type--badge qodef-period--side\">\n\t<div class=\"qodef-m-inner\">\n\t\t\t<div class=\"qodef-m-price\">\n\t\t<div class=\"qodef-m-price-wrapper qodef-h1\">\n\t\t\t\t\t\t\t<span class=\"qodef-m-price-currency\">$<\/span>\n\t\t\t\t\t\t<span class=\"qodef-m-price-value\">105<\/span>\n\t\t<\/div>\n\t\t\t\t\t<span class=\"qodef-m-price-period\">Por mes<\/span>\n\t\t\t<\/div>\n\t\t\t<h4 class=\"qodef-m-title\">\n\t\tMembres\u00eda de 12 meses\t<\/h4>\n\t\t\t\t\t<ol class=\"qodef-m-content\">\n\t\t\t\t\t<li class=\"qodef-e-item\">\n\t\t\t\t\t\t\t\t<span class=\"qodef-e-text\">Sin que perpet.<\/span>\n\t\t\t<\/li>\n\t\t\t<\/ol>\n\t\t\t<div class=\"qodef-m-button qodef-qi-clear\">\n\t\t\t<a class=\"qodef-shortcode qodef-m qodef-qi-button qodef-html--link qodef-layout--filled qodef-type--standard qodef-icon--right qodef-hover--icon-move-horizontal-short\" href=\"https:\/\/hero-tonic.com\/es\/contact\/\" target=\"_self\">\t\t<span class=\"qodef-m-text\">Leer m\u00e1s<\/span>\t\t\t<\/a>\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f437d1 elementor-section-full_width elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"3f437d1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f0de223\" data-id=\"f0de223\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-624ff2e elementor-widget elementor-widget-image\" data-id=\"624ff2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"911\" height=\"831\" src=\"https:\/\/hero-tonic.com\/wp-content\/uploads\/2020\/10\/h1-img-13.jpg\" class=\"attachment-full size-full wp-image-436\" alt=\"a\" srcset=\"https:\/\/hero-tonic.com\/wp-content\/uploads\/2020\/10\/h1-img-13.jpg 911w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2020\/10\/h1-img-13-300x274.jpg 300w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2020\/10\/h1-img-13-768x701.jpg 768w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2020\/10\/h1-img-13-13x12.jpg 13w\" sizes=\"(max-width: 911px) 100vw, 911px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e4438e5\" data-id=\"e4438e5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-930d2f6 elementor-widget-tablet__width-inherit elementor-widget__width-initial elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"930d2f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--underline qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t<h2 class=\"qodef-m-title\">\n\t\t<span class=\"qodef-e-colored\">3<\/span> <span class=\"qodef-e-colored\">ejercicios<\/span> t\u00fa has<br \/> tengo que probar ahora\t<\/h2>\n\t\t\t<div class=\"qodef-m-text\"><p>En cualquier caso, honestidad con \u00e9l. Labores con \u00e9l, y \u00e9l tiene un discurso enga\u00f1oso, y el ilusionismo de \u00e9l con \u00e9l.<\/p><\/div>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb7af87 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-qi_addons_for_elementor_contact_form_7\" data-id=\"cb7af87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_contact_form_7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-contact-form-7\">\n\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f951-o2\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"951\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/pages\/6#wpcf7-f951-o2\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/es\/wp-json\/wp\/v2\/pages\/6#wpcf7-f951-o2\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"951\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f951-o2\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"qodef-grid qodef-layout--columns qodef-col-num--2 qodef-responsive--predefined qodef-gutter--small\">\n<div class=\"qodef-grid-inner clear\">\n\n<div class=\"qodef-grid-item\">\n<span class=\"wpcf7-form-control-wrap\" data-name=\"first-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nombre\" value=\"\" type=\"text\" name=\"first-name\" \/><\/span>\n<\/div>\n\n<div class=\"qodef-grid-item\">\n<span class=\"wpcf7-form-control-wrap\" data-name=\"first-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"N\u00famero de tel\u00e9fono\" value=\"\" type=\"text\" name=\"first-name\" \/><\/span>\n<\/div>\n<\/div>\n<\/div>\n\n\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Tu correo electr\u00f3nico\" value=\"\" type=\"text\" name=\"your-message\" \/><\/span>\n\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Registrarse\" \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6adc4a9 qodef-elementor-content-grid elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6adc4a9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fd6387a\" data-id=\"fd6387a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d75dc7 elementor-widget elementor-widget-qi_addons_for_elementor_blog_list\" data-id=\"2d75dc7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_blog_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-addons-blog-list qodef--list qodef-info-no-icons qodef-image--hover-zoom-out qodef-image--hover-from-left qodef-qi-grid qodef-layout--qi-columns qodef-col-num--2 qodef-item-layout--standard qodef-responsive--predefined\" >\n\t<div class=\"qodef-grid-inner\">\n\t\t<article class=\"qodef-e qodef-blog-item qodef-grid-item qodef-item--full post-635 post type-post status-publish format-standard has-post-thumbnail hentry category-fitness category-lifestyle category-nutrition tag-balance tag-gym tag-workout\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-media\">\n\t\t<div class=\"qodef-e-media-image\">\n\t\t<a itemprop=\"url\" href=\"https:\/\/hero-tonic.com\/es\/fitness-is-a-lifestyle\/\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"874\" src=\"https:\/\/hero-tonic.com\/wp-content\/uploads\/2020\/11\/h-blog-img-1.jpg\" class=\"attachment-full size-full\" alt=\"g\" srcset=\"https:\/\/hero-tonic.com\/wp-content\/uploads\/2020\/11\/h-blog-img-1.jpg 1300w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2020\/11\/h-blog-img-1-300x202.jpg 300w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2020\/11\/h-blog-img-1-1024x688.jpg 1024w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2020\/11\/h-blog-img-1-768x516.jpg 768w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2020\/11\/h-blog-img-1-18x12.jpg 18w\" sizes=\"(max-width: 1300px) 100vw, 1300px\" \/>\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n\t\t<div class=\"qodef-e-content\">\n\t\t\t\t\t\t\t<div class=\"qodef-e-info qodef-info--top\">\n\t\t\t\t\t<div itemprop=\"dateCreated\" class=\"qodef-e-info-item qodef-e-info-date entry-date\">\n\t<a itemprop=\"url\" href=\"https:\/\/hero-tonic.com\/es\/2020\/11\/\">\n\t\t\t\t2 de noviembre de 2020\t<\/a>\n<\/div>\n<div class=\"qodef-e-info-item qodef-e-info-category\">\n\t\t<a href=\"https:\/\/hero-tonic.com\/es\/category\/fitness\/\" rel=\"category tag\">Fitness<\/a><span class=\"qodef-category-separator\"><\/span><a href=\"https:\/\/hero-tonic.com\/es\/category\/lifestyle\/\" rel=\"category tag\">Estilo de vida<\/a><span class=\"qodef-category-separator\"><\/span><a href=\"https:\/\/hero-tonic.com\/es\/category\/nutrition\/\" rel=\"category tag\">Nutrici\u00f3n<\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"qodef-e-text\">\n\t\t\t\t<h3 itemprop=\"name\" class=\"qodef-e-title entry-title\">\n\t<a itemprop=\"url\" class=\"qodef-e-title-link\" href=\"https:\/\/hero-tonic.com\/es\/fitness-is-a-lifestyle\/\">\n\t\tEl fitness es un estilo de vida\t<\/a>\n<\/h3>\n\t\t<p itemprop=\"description\" class=\"qodef-e-excerpt\">\n\t\t\tLa verdad y la justicia me hacen m\u00e1s instructivo, encuentro molestia organizada para m\u00ed. \u00c9l ha concluido la molestia, a \u00e9l le preocupa la molestia. Qui\u00e9n est\u00e1 libre de molestias. El di\u00e1metro concluye para \u00e9l, incluyendo la elocuencia maliciosa.\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/article>\n<article class=\"qodef-e qodef-blog-item qodef-grid-item qodef-item--full post-638 post type-post status-publish format-standard has-post-thumbnail hentry category-fitness category-lifestyle category-nutrition tag-balance tag-gym tag-workout\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-media\">\n\t\t<div class=\"qodef-e-media-image\">\n\t\t<a itemprop=\"url\" href=\"https:\/\/hero-tonic.com\/es\/push-your-boundaries\/\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"874\" src=\"https:\/\/hero-tonic.com\/wp-content\/uploads\/2020\/11\/h-blog-img-2.jpg\" class=\"attachment-full size-full\" alt=\"o\" srcset=\"https:\/\/hero-tonic.com\/wp-content\/uploads\/2020\/11\/h-blog-img-2.jpg 1300w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2020\/11\/h-blog-img-2-300x202.jpg 300w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2020\/11\/h-blog-img-2-1024x688.jpg 1024w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2020\/11\/h-blog-img-2-768x516.jpg 768w, https:\/\/hero-tonic.com\/wp-content\/uploads\/2020\/11\/h-blog-img-2-18x12.jpg 18w\" sizes=\"(max-width: 1300px) 100vw, 1300px\" \/>\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n\t\t<div class=\"qodef-e-content\">\n\t\t\t\t\t\t\t<div class=\"qodef-e-info qodef-info--top\">\n\t\t\t\t\t<div itemprop=\"dateCreated\" class=\"qodef-e-info-item qodef-e-info-date entry-date\">\n\t<a itemprop=\"url\" href=\"https:\/\/hero-tonic.com\/es\/2020\/11\/\">\n\t\t\t\t2 de noviembre de 2020\t<\/a>\n<\/div>\n<div class=\"qodef-e-info-item qodef-e-info-category\">\n\t\t<a href=\"https:\/\/hero-tonic.com\/es\/category\/fitness\/\" rel=\"category tag\">Fitness<\/a><span class=\"qodef-category-separator\"><\/span><a href=\"https:\/\/hero-tonic.com\/es\/category\/lifestyle\/\" rel=\"category tag\">Estilo de vida<\/a><span class=\"qodef-category-separator\"><\/span><a href=\"https:\/\/hero-tonic.com\/es\/category\/nutrition\/\" rel=\"category tag\">Nutrici\u00f3n<\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"qodef-e-text\">\n\t\t\t\t<h3 itemprop=\"name\" class=\"qodef-e-title entry-title\">\n\t<a itemprop=\"url\" class=\"qodef-e-title-link\" href=\"https:\/\/hero-tonic.com\/es\/push-your-boundaries\/\">\n\t\tSupera tus l\u00edmites\t<\/a>\n<\/h3>\n\t\t<p itemprop=\"description\" class=\"qodef-e-excerpt\">\n\t\t\tLa verdad y la justicia me hacen m\u00e1s instructivo, encuentro molestia organizada para m\u00ed. \u00c9l ha concluido la molestia, a \u00e9l le preocupa la molestia. Qui\u00e9n est\u00e1 libre de molestias. El di\u00e1metro concluye para \u00e9l, incluyendo la elocuencia maliciosa.\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/article>\n\t<\/div>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f62d0d6 elementor-section-full_width elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"f62d0d6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f8a181b\" data-id=\"f8a181b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e1ae096 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"e1ae096\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 204.4 173.3\" style=\"enable-background:new 0 0 204.4 173.3; stroke:transparent;\" xml:space=\"preserve\"><style type=\"text\/css\">\t.st20{fill:none;stroke:currentColor;stroke-width:2;}<\/style><g>\t<path class=\"st20\" d=\"M94.4,110c0,34.3-28,62.3-62.3,62.3h-7.8c-4.3,0-7.8-3.5-7.8-7.8v-15.6c0-4.3,3.5-7.8,7.8-7.8h7.8   c17.2,0,31.1-14,31.1-31.1v-3.9c0-6.4-5.2-11.7-11.7-11.7H24.4C11.5,94.4,1,84,1,71.1V24.4C1,11.5,11.5,1,24.4,1h46.7   C84,1,94.4,11.5,94.4,24.4V110z M203.4,110c0,34.3-28,62.3-62.3,62.3h-7.8c-4.3,0-7.8-3.5-7.8-7.8v-15.6c0-4.3,3.5-7.8,7.8-7.8h7.8   c17.2,0,31.1-14,31.1-31.1v-3.9c0-6.4-5.2-11.7-11.7-11.7h-27.3C120.5,94.4,110,84,110,71.1V24.4C110,11.5,120.5,1,133.4,1h46.7   c12.9,0,23.4,10.5,23.4,23.4V110z\"><\/path><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fda4479 elementor-widget elementor-widget-qi_addons_for_elementor_testimonials_slider\" data-id=\"fda4479\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_testimonials_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-testimonials-slider qodef--swiper-fade qodef-qi-grid qodef-qi-swiper-container qodef-item-layout--info-below\" data-options=\"{&quot;direction&quot;:&quot;horizontal&quot;,&quot;slidesPerView&quot;:&quot;1&quot;,&quot;spaceBetween&quot;:30,&quot;spaceBetweenTablet&quot;:30,&quot;spaceBetweenMobile&quot;:30,&quot;effect&quot;:&quot;&quot;,&quot;loop&quot;:true,&quot;autoplay&quot;:true,&quot;centeredSlides&quot;:false,&quot;speed&quot;:&quot;&quot;,&quot;speedAnimation&quot;:&quot;&quot;,&quot;outsideNavigation&quot;:&quot;no&quot;,&quot;outsidePagination&quot;:&quot;no&quot;,&quot;unique&quot;:&quot;1&quot;,&quot;partialValue&quot;:0,&quot;disablePartialValue&quot;:&quot;&quot;,&quot;parallax&quot;:&quot;no&quot;}\">\n\t<div class=\"swiper-wrapper\">\n\t\t<div class=\"qodef-e swiper-slide elementor-repeater-item-183a13c\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t<div class=\"qodef-e-content\">\n\t\t\t\t<div class=\"qodef-e-quote\">\n\t\t<svg class=\"qodef-e-quote-icon\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" x=\"0px\" y=\"0px\" viewbox=\"0 0 190.5 148\" xml:space=\"preserve\"><g><path d=\"M37.7,146.3L2.1,124.6C19.3,100,28.2,74.1,28.8,46.7V2.3H90v38.8c0,19.3-5,38.8-15.1,58.4C64.9,119,52.5,134.6,37.7,146.3z M133.7,146.3l-35.6-21.7c17.2-24.5,26.2-50.5,26.8-77.9V2.3h61.2v38.8c0,19.3-5,38.8-15.1,58.4C160.9,119,148.5,134.6,133.7,146.3z\"\/><\/g><\/svg>\t<\/div>\n\t\t\t\t\t\t\t\t<h3 itemprop=\"description\" class=\"qodef-e-text\">La tierra se cr\u00eda adipiscing para cada t\u00fa. Platea dictumst vestibulo rhoncus est pell entesque.<\/h3>\n\t\t\t\t<div class=\"qodef-e-author\">\n\t\t<h6 class=\"qodef-e-author-name\">Rick Greenwalt<\/h6>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"qodef-e swiper-slide elementor-repeater-item-47a734d\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t<div class=\"qodef-e-content\">\n\t\t\t\t<div class=\"qodef-e-quote\">\n\t\t<svg class=\"qodef-e-quote-icon\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" x=\"0px\" y=\"0px\" viewbox=\"0 0 190.5 148\" xml:space=\"preserve\"><g><path d=\"M37.7,146.3L2.1,124.6C19.3,100,28.2,74.1,28.8,46.7V2.3H90v38.8c0,19.3-5,38.8-15.1,58.4C64.9,119,52.5,134.6,37.7,146.3z M133.7,146.3l-35.6-21.7c17.2-24.5,26.2-50.5,26.8-77.9V2.3h61.2v38.8c0,19.3-5,38.8-15.1,58.4C160.9,119,148.5,134.6,133.7,146.3z\"\/><\/g><\/svg>\t<\/div>\n\t\t\t\t\t\t\t\t<h3 itemprop=\"description\" class=\"qodef-e-text\">Y el mobiliario desea el ultrices de la selecci\u00f3n de gravidad. Placerat vest\u00edbulo lectus mauris ultrices.<\/h3>\n\t\t\t\t<div class=\"qodef-e-author\">\n\t\t<h6 class=\"qodef-e-author-name\">Bernard Curtis<\/h6>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"qodef-e swiper-slide elementor-repeater-item-713872f\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t<div class=\"qodef-e-content\">\n\t\t\t\t<div class=\"qodef-e-quote\">\n\t\t<svg class=\"qodef-e-quote-icon\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" x=\"0px\" y=\"0px\" viewbox=\"0 0 190.5 148\" xml:space=\"preserve\"><g><path d=\"M37.7,146.3L2.1,124.6C19.3,100,28.2,74.1,28.8,46.7V2.3H90v38.8c0,19.3-5,38.8-15.1,58.4C64.9,119,52.5,134.6,37.7,146.3z M133.7,146.3l-35.6-21.7c17.2-24.5,26.2-50.5,26.8-77.9V2.3h61.2v38.8c0,19.3-5,38.8-15.1,58.4C160.9,119,148.5,134.6,133.7,146.3z\"\/><\/g><\/svg>\t<\/div>\n\t\t\t\t\t\t\t\t<h3 itemprop=\"description\" class=\"qodef-e-text\">Massa tincidunt nunc pulvinar sapien et ligula ullamcorper malesuada. Tincidunt vitae semper.<\/h3>\n\t\t\t\t<div class=\"qodef-e-author\">\n\t\t<h6 class=\"qodef-e-author-name\">Mark Kappel<\/h6>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t<\/div>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9ea7a24 elementor-section-full_width elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"9ea7a24\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0c627d1\" data-id=\"0c627d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>HERO TONIC MEMBERSHIP $24.95\/month PASSIONATE EXPERTS ENERGIZING LIVES. Pro ne aeterno aperiam intellegat. Velit regione quaeque cu nam, mei delenit paulo maluisset argumentum, mei mazim dolor mentitum cu. Vis ea equidem forensibus, ut vix audiam viderer fabellas, at alia molestie ocurreret mel. Nobis noster graeco no vis, mazim explicari comprehensa sea id. Sit ullum delectus [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2460,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"qi-full-width.php","meta":{"content-type":"","footnotes":""},"class_list":["post-6","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hero Tonic<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hero-tonic.com\/es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hero Tonic\" \/>\n<meta property=\"og:description\" content=\"HERO TONIC MEMBERSHIP $24.95\/month PASSIONATE EXPERTS ENERGIZING LIVES. Pro ne aeterno aperiam intellegat. Velit regione quaeque cu nam, mei delenit paulo maluisset argumentum, mei mazim dolor mentitum cu. Vis ea equidem forensibus, ut vix audiam viderer fabellas, at alia molestie ocurreret mel. Nobis noster graeco no vis, mazim explicari comprehensa sea id. Sit ullum delectus [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hero-tonic.com\/es\/\" \/>\n<meta property=\"og:site_name\" content=\"Hero Tonic\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-06T18:48:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hero-tonic.com\/wp-content\/uploads\/2026\/04\/HERO-TONIC_black-scaled.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2041\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hero-tonic.com\\\/\",\"url\":\"https:\\\/\\\/hero-tonic.com\\\/\",\"name\":\"Hero Tonic\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hero-tonic.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hero-tonic.com\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hero-tonic.com\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hero-tonic.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/HERO-TONIC_black-scaled.png\",\"datePublished\":\"2020-10-29T08:43:43+00:00\",\"dateModified\":\"2026-04-06T18:48:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hero-tonic.com\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hero-tonic.com\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/hero-tonic.com\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hero-tonic.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/HERO-TONIC_black-scaled.png\",\"contentUrl\":\"https:\\\/\\\/hero-tonic.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/HERO-TONIC_black-scaled.png\",\"width\":2560,\"height\":2041},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hero-tonic.com\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hero-tonic.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hero-tonic.com\\\/#website\",\"url\":\"https:\\\/\\\/hero-tonic.com\\\/\",\"name\":\"Hero Tonic\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hero-tonic.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00f3nico Hero","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hero-tonic.com\/es\/","og_locale":"es_ES","og_type":"article","og_title":"Hero Tonic","og_description":"HERO TONIC MEMBERSHIP $24.95\/month PASSIONATE EXPERTS ENERGIZING LIVES. Pro ne aeterno aperiam intellegat. Velit regione quaeque cu nam, mei delenit paulo maluisset argumentum, mei mazim dolor mentitum cu. Vis ea equidem forensibus, ut vix audiam viderer fabellas, at alia molestie ocurreret mel. Nobis noster graeco no vis, mazim explicari comprehensa sea id. Sit ullum delectus [&hellip;]","og_url":"https:\/\/hero-tonic.com\/es\/","og_site_name":"Hero Tonic","article_modified_time":"2026-04-06T18:48:27+00:00","og_image":[{"width":2560,"height":2041,"url":"https:\/\/hero-tonic.com\/wp-content\/uploads\/2026\/04\/HERO-TONIC_black-scaled.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hero-tonic.com\/","url":"https:\/\/hero-tonic.com\/","name":"T\u00f3nico Hero","isPartOf":{"@id":"https:\/\/hero-tonic.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hero-tonic.com\/#primaryimage"},"image":{"@id":"https:\/\/hero-tonic.com\/#primaryimage"},"thumbnailUrl":"https:\/\/hero-tonic.com\/wp-content\/uploads\/2026\/04\/HERO-TONIC_black-scaled.png","datePublished":"2020-10-29T08:43:43+00:00","dateModified":"2026-04-06T18:48:27+00:00","breadcrumb":{"@id":"https:\/\/hero-tonic.com\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hero-tonic.com\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/hero-tonic.com\/#primaryimage","url":"https:\/\/hero-tonic.com\/wp-content\/uploads\/2026\/04\/HERO-TONIC_black-scaled.png","contentUrl":"https:\/\/hero-tonic.com\/wp-content\/uploads\/2026\/04\/HERO-TONIC_black-scaled.png","width":2560,"height":2041},{"@type":"BreadcrumbList","@id":"https:\/\/hero-tonic.com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hero-tonic.com\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/hero-tonic.com\/#website","url":"https:\/\/hero-tonic.com\/","name":"T\u00f3nico Hero","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hero-tonic.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"}]}},"_links":{"self":[{"href":"https:\/\/hero-tonic.com\/es\/wp-json\/wp\/v2\/pages\/6","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hero-tonic.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hero-tonic.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hero-tonic.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hero-tonic.com\/es\/wp-json\/wp\/v2\/comments?post=6"}],"version-history":[{"count":33,"href":"https:\/\/hero-tonic.com\/es\/wp-json\/wp\/v2\/pages\/6\/revisions"}],"predecessor-version":[{"id":2544,"href":"https:\/\/hero-tonic.com\/es\/wp-json\/wp\/v2\/pages\/6\/revisions\/2544"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hero-tonic.com\/es\/wp-json\/wp\/v2\/media\/2460"}],"wp:attachment":[{"href":"https:\/\/hero-tonic.com\/es\/wp-json\/wp\/v2\/media?parent=6"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}